{"id":22286,"date":"2017-01-25T09:33:32","date_gmt":"2017-01-25T08:33:32","guid":{"rendered":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/15878009_1336570409739533_769586908_o.jpg"},"modified":"2017-01-25T09:33:32","modified_gmt":"2017-01-25T08:33:32","slug":"15878009_1336570409739533_769586908_o-2","status":"inherit","type":"attachment","link":"https:\/\/www.wineinsicily.com\/en\/15878009_1336570409739533_769586908_o-2\/","title":{"rendered":"15878009_1336570409739533_769586908_o"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-22286","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/15878009_1336570409739533_769586908_o.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/15878009_1336570409739533_769586908_o-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/15878009_1336570409739533_769586908_o-300x169.jpg 300w, https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/15878009_1336570409739533_769586908_o-600x338.jpg 600w, https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/15878009_1336570409739533_769586908_o.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":960,"height":540,"file":"2017\/01\/15878009_1336570409739533_769586908_o.jpg","sizes":{"thumbnail":{"file":"15878009_1336570409739533_769586908_o-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/15878009_1336570409739533_769586908_o-150x150.jpg"},"medium":{"file":"15878009_1336570409739533_769586908_o-300x169.jpg","width":300,"height":169,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/15878009_1336570409739533_769586908_o-300x169.jpg"},"wysija-newsletters-max":{"file":"15878009_1336570409739533_769586908_o-600x338.jpg","width":600,"height":338,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/15878009_1336570409739533_769586908_o-600x338.jpg"},"readanddigest_square":{"file":"15878009_1336570409739533_769586908_o-550x540.jpg","width":550,"height":540,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/15878009_1336570409739533_769586908_o-550x540.jpg"},"readanddigest_landscape":{"file":"15878009_1336570409739533_769586908_o-800x540.jpg","width":800,"height":540,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/15878009_1336570409739533_769586908_o-800x540.jpg"},"readanddigest_portrait":{"file":"15878009_1336570409739533_769586908_o-600x540.jpg","width":600,"height":540,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/15878009_1336570409739533_769586908_o-600x540.jpg"},"readanddigest_thumb":{"file":"15878009_1336570409739533_769586908_o-128x86.jpg","width":128,"height":86,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/15878009_1336570409739533_769586908_o-128x86.jpg"},"readanddigest_large_height":{"file":"15878009_1336570409739533_769586908_o-550x540.jpg","width":550,"height":540,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/15878009_1336570409739533_769586908_o-550x540.jpg"},"full":{"file":"15878009_1336570409739533_769586908_o.jpg","width":960,"height":540,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/15878009_1336570409739533_769586908_o.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/15878009_1336570409739533_769586908_o.jpg","filename":"15878009_1336570409739533_769586908_o.jpg","filesize":346941,"_links":{"self":[{"href":"https:\/\/www.wineinsicily.com\/en\/wp-json\/wp\/v2\/media\/22286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wineinsicily.com\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.wineinsicily.com\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.wineinsicily.com\/en\/wp-json\/wp\/v2\/users\/2"}]}}