{"id":22289,"date":"2017-01-25T09:33:44","date_gmt":"2017-01-25T08:33:44","guid":{"rendered":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/16107184_1810035039264240_1302366063452263682_o.jpg"},"modified":"2017-01-25T09:33:44","modified_gmt":"2017-01-25T08:33:44","slug":"16107184_1810035039264240_1302366063452263682_o-2","status":"inherit","type":"attachment","link":"https:\/\/www.wineinsicily.com\/en\/16107184_1810035039264240_1302366063452263682_o-2\/","title":{"rendered":"16107184_1810035039264240_1302366063452263682_o"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-22289","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/16107184_1810035039264240_1302366063452263682_o.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/16107184_1810035039264240_1302366063452263682_o-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/16107184_1810035039264240_1302366063452263682_o-300x225.jpg 300w, https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/16107184_1810035039264240_1302366063452263682_o-600x450.jpg 600w, https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/16107184_1810035039264240_1302366063452263682_o-800x600.jpg 800w, https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/16107184_1810035039264240_1302366063452263682_o.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":960,"height":720,"file":"2017\/01\/16107184_1810035039264240_1302366063452263682_o.jpg","sizes":{"thumbnail":{"file":"16107184_1810035039264240_1302366063452263682_o-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/16107184_1810035039264240_1302366063452263682_o-150x150.jpg"},"medium":{"file":"16107184_1810035039264240_1302366063452263682_o-300x225.jpg","width":300,"height":225,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/16107184_1810035039264240_1302366063452263682_o-300x225.jpg"},"wysija-newsletters-max":{"file":"16107184_1810035039264240_1302366063452263682_o-600x450.jpg","width":600,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/16107184_1810035039264240_1302366063452263682_o-600x450.jpg"},"readanddigest_square":{"file":"16107184_1810035039264240_1302366063452263682_o-550x550.jpg","width":550,"height":550,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/16107184_1810035039264240_1302366063452263682_o-550x550.jpg"},"readanddigest_landscape":{"file":"16107184_1810035039264240_1302366063452263682_o-800x600.jpg","width":800,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/16107184_1810035039264240_1302366063452263682_o-800x600.jpg"},"readanddigest_portrait":{"file":"16107184_1810035039264240_1302366063452263682_o-600x720.jpg","width":600,"height":720,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/16107184_1810035039264240_1302366063452263682_o-600x720.jpg"},"readanddigest_thumb":{"file":"16107184_1810035039264240_1302366063452263682_o-128x86.jpg","width":128,"height":86,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/16107184_1810035039264240_1302366063452263682_o-128x86.jpg"},"readanddigest_single_post_title":{"file":"16107184_1810035039264240_1302366063452263682_o-960x580.jpg","width":960,"height":580,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/16107184_1810035039264240_1302366063452263682_o-960x580.jpg"},"readanddigest_large_width":{"file":"16107184_1810035039264240_1302366063452263682_o-960x550.jpg","width":960,"height":550,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/16107184_1810035039264240_1302366063452263682_o-960x550.jpg"},"readanddigest_large_height":{"file":"16107184_1810035039264240_1302366063452263682_o-550x720.jpg","width":550,"height":720,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/16107184_1810035039264240_1302366063452263682_o-550x720.jpg"},"full":{"file":"16107184_1810035039264240_1302366063452263682_o.jpg","width":960,"height":720,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/16107184_1810035039264240_1302366063452263682_o.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2017\/01\/16107184_1810035039264240_1302366063452263682_o.jpg","filename":"16107184_1810035039264240_1302366063452263682_o.jpg","filesize":341143,"_links":{"self":[{"href":"https:\/\/www.wineinsicily.com\/en\/wp-json\/wp\/v2\/media\/22289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wineinsicily.com\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.wineinsicily.com\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.wineinsicily.com\/en\/wp-json\/wp\/v2\/users\/2"}]}}