{"id":23581,"date":"2019-08-05T18:12:58","date_gmt":"2019-08-05T16:12:58","guid":{"rendered":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2019\/08\/67762346_2537746869603437_7979841325191135232_o.jpg"},"modified":"2019-08-05T18:12:58","modified_gmt":"2019-08-05T16:12:58","slug":"67762346_2537746869603437_7979841325191135232_o-2","status":"inherit","type":"attachment","link":"https:\/\/www.wineinsicily.com\/en\/67762346_2537746869603437_7979841325191135232_o-2\/","title":{"rendered":"67762346_2537746869603437_7979841325191135232_o"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-23581","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2019\/08\/67762346_2537746869603437_7979841325191135232_o.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2019\/08\/67762346_2537746869603437_7979841325191135232_o-300x169.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2019\/08\/67762346_2537746869603437_7979841325191135232_o-300x169.jpg 300w, https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2019\/08\/67762346_2537746869603437_7979841325191135232_o-1024x576.jpg 1024w, https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2019\/08\/67762346_2537746869603437_7979841325191135232_o-600x338.jpg 600w, https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2019\/08\/67762346_2537746869603437_7979841325191135232_o-1200x675.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2048,"height":1152,"file":"2019\/08\/67762346_2537746869603437_7979841325191135232_o.jpg","sizes":{"thumbnail":{"file":"67762346_2537746869603437_7979841325191135232_o-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2019\/08\/67762346_2537746869603437_7979841325191135232_o-150x150.jpg"},"medium":{"file":"67762346_2537746869603437_7979841325191135232_o-300x169.jpg","width":300,"height":169,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2019\/08\/67762346_2537746869603437_7979841325191135232_o-300x169.jpg"},"large":{"file":"67762346_2537746869603437_7979841325191135232_o-1024x576.jpg","width":1024,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2019\/08\/67762346_2537746869603437_7979841325191135232_o-1024x576.jpg"},"wysija-newsletters-max":{"file":"67762346_2537746869603437_7979841325191135232_o-600x338.jpg","width":600,"height":338,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2019\/08\/67762346_2537746869603437_7979841325191135232_o-600x338.jpg"},"readanddigest_square":{"file":"67762346_2537746869603437_7979841325191135232_o-550x550.jpg","width":550,"height":550,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2019\/08\/67762346_2537746869603437_7979841325191135232_o-550x550.jpg"},"readanddigest_landscape":{"file":"67762346_2537746869603437_7979841325191135232_o-800x600.jpg","width":800,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2019\/08\/67762346_2537746869603437_7979841325191135232_o-800x600.jpg"},"readanddigest_portrait":{"file":"67762346_2537746869603437_7979841325191135232_o-600x800.jpg","width":600,"height":800,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2019\/08\/67762346_2537746869603437_7979841325191135232_o-600x800.jpg"},"readanddigest_post_feature_image":{"file":"67762346_2537746869603437_7979841325191135232_o-1200x675.jpg","width":1200,"height":675,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2019\/08\/67762346_2537746869603437_7979841325191135232_o-1200x675.jpg"},"readanddigest_thumb":{"file":"67762346_2537746869603437_7979841325191135232_o-128x86.jpg","width":128,"height":86,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2019\/08\/67762346_2537746869603437_7979841325191135232_o-128x86.jpg"},"readanddigest_single_post_title":{"file":"67762346_2537746869603437_7979841325191135232_o-1200x580.jpg","width":1200,"height":580,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2019\/08\/67762346_2537746869603437_7979841325191135232_o-1200x580.jpg"},"readanddigest_large_width":{"file":"67762346_2537746869603437_7979841325191135232_o-1100x550.jpg","width":1100,"height":550,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2019\/08\/67762346_2537746869603437_7979841325191135232_o-1100x550.jpg"},"readanddigest_large_height":{"file":"67762346_2537746869603437_7979841325191135232_o-550x1100.jpg","width":550,"height":1100,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2019\/08\/67762346_2537746869603437_7979841325191135232_o-550x1100.jpg"},"photowinetour":{"file":"67762346_2537746869603437_7979841325191135232_o-780x338.jpg","width":780,"height":338,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2019\/08\/67762346_2537746869603437_7979841325191135232_o-780x338.jpg"},"full":{"file":"67762346_2537746869603437_7979841325191135232_o.jpg","width":2048,"height":1152,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2019\/08\/67762346_2537746869603437_7979841325191135232_o.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2019\/08\/67762346_2537746869603437_7979841325191135232_o.jpg","filename":"67762346_2537746869603437_7979841325191135232_o.jpg","filesize":124469,"_links":{"self":[{"href":"https:\/\/www.wineinsicily.com\/en\/wp-json\/wp\/v2\/media\/23581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wineinsicily.com\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.wineinsicily.com\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.wineinsicily.com\/en\/wp-json\/wp\/v2\/users\/2"}]}}