{"id":35406,"date":"2022-09-08T13:40:12","date_gmt":"2022-09-08T11:40:12","guid":{"rendered":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2022\/09\/2.-MONTE-CIRAMI.jpeg"},"modified":"2022-09-08T13:40:12","modified_gmt":"2022-09-08T11:40:12","slug":"2-monte-cirami-2","status":"inherit","type":"attachment","link":"https:\/\/www.wineinsicily.com\/en\/2-monte-cirami-2\/","title":{"rendered":"2. MONTE CIRAMI"},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-35406","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2022\/09\/2.-MONTE-CIRAMI.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2022\/09\/2.-MONTE-CIRAMI-300x200.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2022\/09\/2.-MONTE-CIRAMI-300x200.jpeg 300w, https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2022\/09\/2.-MONTE-CIRAMI-600x400.jpeg 600w, https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2022\/09\/2.-MONTE-CIRAMI-128x86.jpeg 128w, https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2022\/09\/2.-MONTE-CIRAMI.jpeg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1024,"height":682,"file":"2022\/09\/2.-MONTE-CIRAMI.jpeg","filesize":137858,"sizes":{"medium":{"file":"2.-MONTE-CIRAMI-300x200.jpeg","width":300,"height":200,"filesize":15429,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2022\/09\/2.-MONTE-CIRAMI-300x200.jpeg"},"thumbnail":{"file":"2.-MONTE-CIRAMI-150x150.jpeg","width":150,"height":150,"filesize":6462,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2022\/09\/2.-MONTE-CIRAMI-150x150.jpeg"},"wysija-newsletters-max":{"file":"2.-MONTE-CIRAMI-600x400.jpeg","width":600,"height":400,"filesize":56289,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2022\/09\/2.-MONTE-CIRAMI-600x400.jpeg"},"readanddigest_square":{"file":"2.-MONTE-CIRAMI-550x550.jpeg","width":550,"height":550,"filesize":70209,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2022\/09\/2.-MONTE-CIRAMI-550x550.jpeg"},"readanddigest_landscape":{"file":"2.-MONTE-CIRAMI-800x600.jpeg","width":800,"height":600,"filesize":107066,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2022\/09\/2.-MONTE-CIRAMI-800x600.jpeg"},"readanddigest_portrait":{"file":"2.-MONTE-CIRAMI-600x682.jpeg","width":600,"height":682,"filesize":105791,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2022\/09\/2.-MONTE-CIRAMI-600x682.jpeg"},"readanddigest_thumb":{"file":"2.-MONTE-CIRAMI-128x86.jpeg","width":128,"height":86,"filesize":3490,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2022\/09\/2.-MONTE-CIRAMI-128x86.jpeg"},"readanddigest_single_post_title":{"file":"2.-MONTE-CIRAMI-1024x580.jpeg","width":1024,"height":580,"filesize":150466,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2022\/09\/2.-MONTE-CIRAMI-1024x580.jpeg"},"readanddigest_large_width":{"file":"2.-MONTE-CIRAMI-1024x550.jpeg","width":1024,"height":550,"filesize":142271,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2022\/09\/2.-MONTE-CIRAMI-1024x550.jpeg"},"readanddigest_large_height":{"file":"2.-MONTE-CIRAMI-550x682.jpeg","width":550,"height":682,"filesize":97208,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2022\/09\/2.-MONTE-CIRAMI-550x682.jpeg"},"photowinetour":{"file":"2.-MONTE-CIRAMI-780x338.jpeg","width":780,"height":338,"filesize":63857,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2022\/09\/2.-MONTE-CIRAMI-780x338.jpeg"},"full":{"file":"2.-MONTE-CIRAMI.jpeg","width":1024,"height":682,"mime_type":"image\/jpeg","source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2022\/09\/2.-MONTE-CIRAMI.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/wineinsicilycom.cdn-immedia.net\/wp-content\/uploads\/2022\/09\/2.-MONTE-CIRAMI.jpeg","filename":"2.-MONTE-CIRAMI.jpeg","filesize":137858,"_links":{"self":[{"href":"https:\/\/www.wineinsicily.com\/en\/wp-json\/wp\/v2\/media\/35406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wineinsicily.com\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.wineinsicily.com\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.wineinsicily.com\/en\/wp-json\/wp\/v2\/users\/2"}]}}